{"id":9328,"date":"2014-04-16T14:55:00","date_gmt":"2014-04-16T17:55:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ler_e_ler\/"},"modified":"2014-04-16T14:55:00","modified_gmt":"2014-04-16T17:55:00","slug":"ler_e_ler","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ler_e_ler\/","title":{"rendered":"Ler e ler"},"content":{"rendered":"<p><b> <\/b>  <\/p>\n<p>&#8220;Os  homens n\u00e3o sabem ler. Aplicam a um poema o mesmo processo que aplicam a   an\u00fancios de jornal ou a not\u00edcias de propaganda pol\u00edtica: contentam-se  com o  sentido superficial das palavras, sem explorar a inten\u00e7\u00e3o de quem  fala.  Confundem duas coisas que est\u00e3o juntas em cada palavra falada ou  escrita: a  express\u00e3o e a inten\u00e7\u00e3o.&#8221; (Otto Maria Carpeaux)   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Os homens n\u00e3o sabem ler. Aplicam a um poema o mesmo processo que aplicam a an\u00fancios de jornal ou a not\u00edcias de propaganda pol\u00edtica: contentam-se com o sentido superficial das palavras, sem explorar a inten\u00e7\u00e3o de quem fala. Confundem duas coisas que est\u00e3o juntas em cada palavra falada ou escrita: a express\u00e3o e a inten\u00e7\u00e3o.&#8221; (Otto Maria Carpeaux)<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9328","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9328"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9328\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}