{"id":9313,"date":"2014-09-09T10:00:00","date_gmt":"2014-09-09T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/vilao_da_lingua\/"},"modified":"2014-09-09T10:00:00","modified_gmt":"2014-09-09T13:00:00","slug":"vilao_da_lingua","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/vilao_da_lingua\/","title":{"rendered":"Vil\u00e3o da l\u00edngua?"},"content":{"rendered":"\n<p> Era manh\u00e3 de segunda-feira. Concei\u00e7\u00e3o, como sempre  faz, ouvia a CBN. O programa corria solto  e animado. Com entusiasmo, o apresentador se referia a mocinhos e a bandidos. De  repente, n\u00e3o mais que de repente, convocou &#8220;vil\u00f5es e viloas&#8221;. Ops!    <\/p>\n<p>Ouvintes ligaram. Mandaram mensagens por e-mail.  Tuitaram. Est\u00eav\u00e3o voltou atr\u00e1s. &#8220;Vil\u00f5es e vil\u00e3s&#8221;, repetia sem parar. Com a pulga  atr\u00e1s da orelha, foi ao Aur\u00e9lio. L\u00e1 estava. Vil\u00e3o tem dois femininos.  Um: vil\u00e3. O outro: viloa. Ele respirou aliviado. Escapou do risco de se tornar  vil\u00e3o da l\u00edngua. Ufa!   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era manh\u00e3 de segunda-feira. Concei\u00e7\u00e3o, como sempre faz, ouvia a CBN. O programa corria solto e animado. Com entusiasmo, o apresentador se referia a mocinhos e a bandidos. De repente, n\u00e3o mais que de repente, convocou &#8220;vil\u00f5es e viloas&#8221;. Ops! Ouvintes ligaram. Mandaram mensagens por e-mail. Tuitaram. Est\u00eav\u00e3o voltou atr\u00e1s. &#8220;Vil\u00f5es e vil\u00e3s&#8221;, repetia sem parar. Com a pulga atr\u00e1s da orelha, foi ao Aur\u00e9lio. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9313","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9313"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9313\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}