{"id":9309,"date":"2014-04-12T00:00:00","date_gmt":"2014-04-12T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/diquinha_infantil_14\/"},"modified":"2015-12-10T11:19:16","modified_gmt":"2015-12-10T13:19:16","slug":"diquinha_infantil_14","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/diquinha_infantil_14\/","title":{"rendered":"Diquinha infantil 14"},"content":{"rendered":"\n<p><b>A 1\u00aa viagem de Simbad, o marujo <\/b> <\/p>\n<p>Lembra-se? Sherazade contou hist\u00f3rias durante 1.001 noites. Valeu. Salvou a vida e nos apresentou mont\u00f5es de personagens. Um deles \u00e9 Simbad. Ele nasceu em Bagd\u00e1, l\u00e1 no Oriente M\u00e9dio. Louco por aventuras, Simbad virou marinheiro e navegou por este mund\u00e3o afora. Queria ficar muiiiiiiiiiiito rico.  <\/p>\n<p>Fez sete viagens. Encontrou povos estranhos, seres monstruosos e fen\u00f4menos fant\u00e1sticos. Na primeira, pegou um navio que o levaria para bem longe. Depois de semanas, desembarcou numa ilha. Estava escuro. Ao acender o fogo, ops! A terra se mexeu. Ele estava em cima de uma baleia gigante.   <\/p>\n<p>Ela abanou o rabo e o jogou no fundo do mar. Que med\u00e3o! Ele, bom nadador, sobreviveu. Voltou pra casa rapidinho. Mas n\u00e3o resistiu por muito tempo. Pouco depois, pegou outra vez o navio. E outra aventura aconteceu.  <\/p>\n<p><b>Gente de mentirinha <\/b> <\/p>\n<p>Personagem \u00e9 gente de mentirinha. Vive em novelas, filmes, revistas, romances. Simbad \u00e9 personagem do livro 1.000 noites. M\u00f4nica, Cebolinha, Magali e Casc\u00e3o s\u00e3o personagens do reino dos quadrinhos.  <\/p>\n<p><b> <\/p>\n<p>Bichos e coisas  <\/b> <\/p>\n<p>Bichos e coisas tamb\u00e9m podem ser personagens. A baleia \u00e9 personagem da primeira viagem de Simbad. O cachorrinho Bidu \u00e9 personagem da Turma da M\u00f4nica. A espada Excalibur \u00e9 personagem do rei Artur.  <\/p>\n<p><b>Sabia? <\/b> <\/p>\n<p>Personagem pode ser feminino e masculino. A gente pode dizer:   <\/p>\n<p>Simbad \u00e9 um personagem das 1.001 noites.   <\/p>\n<p>Simbad \u00e9 uma personagem das 1.001 noites.  <\/p>\n<p><b>Agora voc\u00ea <\/b> <\/p>\n<p>Escreva o nome de tr\u00eas personagens que voc\u00ea acha bem legais:  <\/p>\n<p>1.  <\/p>\n<p>2.  <\/p>\n<p>3.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 1\u00aa viagem de Simbad, o marujo Lembra-se? Sherazade contou hist\u00f3rias durante 1.001 noites. Valeu. Salvou a vida e nos apresentou mont\u00f5es de personagens. Um deles \u00e9 Simbad. Ele nasceu em Bagd\u00e1, l\u00e1 no Oriente M\u00e9dio. Louco por aventuras, Simbad virou marinheiro e navegou por este mund\u00e3o afora. Queria ficar muiiiiiiiiiiito rico. Fez sete viagens. Encontrou povos estranhos, seres monstruosos e fen\u00f4menos fant\u00e1sticos. Na primeira, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-9309","post","type-post","status-publish","format-standard","hentry","category-diquinhas"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9309"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9309\/revisions"}],"predecessor-version":[{"id":11650,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9309\/revisions\/11650"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}