{"id":9282,"date":"2014-12-30T14:20:00","date_gmt":"2014-12-30T16:20:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1253\/"},"modified":"2015-11-12T12:17:33","modified_gmt":"2015-11-12T14:17:33","slug":"erramos-1253","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1253\/","title":{"rendered":"Erramos"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>&#8220;O Jardim Bot\u00e2nico, a \u00c1gua Mineral e o Zoo abrem amanh\u00e3, e fecham no dia 1\u00ba&#8221;,  escrevemos na capa. Reparou? A \u00faltima v\u00edrgula liga ora\u00e7\u00f5es coordenadas. Elas t\u00eam  o mesmo sujeito e n\u00e3o induzem a dupla leitura. O sinalzinho, por isso, sobra.  Melhor: <i>O Jardim Bot\u00e2nico, a \u00c1gua Mineral e o Zoo abrem amanh\u00e3 e fecham no  dia 1\u00ba.<\/i> <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O Jardim Bot\u00e2nico, a \u00c1gua Mineral e o Zoo abrem amanh\u00e3, e fecham no dia 1\u00ba&#8221;, escrevemos na capa. Reparou? A \u00faltima v\u00edrgula liga ora\u00e7\u00f5es coordenadas. Elas t\u00eam o mesmo sujeito e n\u00e3o induzem a dupla leitura. O sinalzinho, por isso, sobra. Melhor: O Jardim Bot\u00e2nico, a \u00c1gua Mineral e o Zoo abrem amanh\u00e3 e fecham no dia 1\u00ba. &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-9282","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9282"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9282\/revisions"}],"predecessor-version":[{"id":9465,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9282\/revisions\/9465"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}