{"id":9275,"date":"2014-12-30T00:00:00","date_gmt":"2014-12-30T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/para_luce_pereira\/"},"modified":"2014-12-30T00:00:00","modified_gmt":"2014-12-30T02:00:00","slug":"para_luce_pereira","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/para_luce_pereira\/","title":{"rendered":"Para Luce Pereira"},"content":{"rendered":"\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<\/div>\n<p>Luce,<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><\/div>\n<p>Seu texto ia bem. At\u00e9 quando voc\u00ea escreveu: &#8220;&#8230; ficando  muito distante das duas &#8220;melhores colocadas&#8221;. A\u00ed  entortou.<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><\/div>\n<p>A reforminha ortogr\u00e1fica n\u00e3o alterou essa constru\u00e7\u00e3o  gramatical. Voc\u00ea hoje est\u00e1 &#8220;melhor vestida&#8221;? Ou est\u00e1 mais bem vestida? Os alunos do primeiro ano est\u00e3o mais bem preparados do que os do segundo ano. Eles N\u00c3O est\u00e3o &#8220;melhores preparados&#8221;. Jamais. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><\/div>\n<p>Portanto,  lembre-se: diante do partic\u00edpio, s\u00f3 a duplinha tem vez. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><\/div>\n<div>Cordialmente   <\/p>\n<p>Jos\u00e9 Fernandes Costa   <\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Luce, Seu texto ia bem. At\u00e9 quando voc\u00ea escreveu: &#8220;&#8230; ficando muito distante das duas &#8220;melhores colocadas&#8221;. A\u00ed entortou. A reforminha ortogr\u00e1fica n\u00e3o alterou essa constru\u00e7\u00e3o gramatical. Voc\u00ea hoje est\u00e1 &#8220;melhor vestida&#8221;? Ou est\u00e1 mais bem vestida? Os alunos do primeiro ano est\u00e3o mais bem preparados do que os do segundo ano. Eles N\u00c3O est\u00e3o &#8220;melhores preparados&#8221;. Jamais. Portanto, lembre-se: diante do partic\u00edpio, s\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9275","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9275"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9275\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}