{"id":9257,"date":"2014-09-01T10:00:00","date_gmt":"2014-09-01T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/entre_tapas_e_beijos_5\/"},"modified":"2014-09-01T10:00:00","modified_gmt":"2014-09-01T13:00:00","slug":"entre_tapas_e_beijos_5","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/entre_tapas_e_beijos_5\/","title":{"rendered":"Entre tapas e beijos 5"},"content":{"rendered":"<p><b> <\/p>\n<p>Pronome eu<\/b>  <\/p>\n<p>N\u00e3o  importa o partido. Nem o sexo. Nem a idade. Os candidatos t\u00eam uma   caracter\u00edstica comum. S\u00e3o eg\u00f3latras. Adoram-se acima de tudo. Sem  mod\u00e9stia,  rivalizam com Deus. Por isso, o eu \u00e9 a grande vedete dos palanques eletr\u00f4nicos. Ao us\u00e1-lo, por\u00e9m,&nbsp;os pid\u00f5es caem em cilada que arrepia cabelos e  afugenta&nbsp;amigos, inimigos e nem uma coisa  nem outra.   <\/p>\n<p>&#8220;Entre  eu e o eleitor&#8221;, dizem uns. &#8220;Entre eu e minha equipe&#8221;, outros.   Valha-nos, Deus! Na egolatria, homens e mulheres n\u00e3o deixam d\u00favida \u2014  foram maus  alunos ou mataram aula. N\u00e3o aprenderam que o pronome eu tem alergia \u00e0  preposi\u00e7\u00e3o. Antecedido por ela, bate asas e d\u00e1 a vez ao irm\u00e3ozinho mim:  <i>Gosta de mim. Trabalha para mim e para voc\u00ea. Nada existe entre mim e o  eleitor. S\u00f3 existe entre mim e minha equipe.<\/i><b> &nbsp;  <\/p>\n<p><\/b>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pronome eu N\u00e3o importa o partido. Nem o sexo. Nem a idade. Os candidatos t\u00eam uma caracter\u00edstica comum. S\u00e3o eg\u00f3latras. Adoram-se acima de tudo. Sem mod\u00e9stia, rivalizam com Deus. Por isso, o eu \u00e9 a grande vedete dos palanques eletr\u00f4nicos. Ao us\u00e1-lo, por\u00e9m,&nbsp;os pid\u00f5es caem em cilada que arrepia cabelos e afugenta&nbsp;amigos, inimigos e nem uma coisa nem outra. &#8220;Entre eu e o eleitor&#8221;, dizem [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9257","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9257"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9257\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}