{"id":9226,"date":"2014-12-23T16:00:00","date_gmt":"2014-12-23T18:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1246\/"},"modified":"2015-11-12T12:17:36","modified_gmt":"2015-11-12T14:17:36","slug":"erramos-1246-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1246-2\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>&#8220;E as abelhas, atra\u00eddas pela cores vibrantes, cumprem um dos seus papeis na  natureza&#8221;, escrevemos na p\u00e1g. 22. Olho vivo! A reforma ortogr\u00e1fica cassou o  acento dos ditongos abertos ei e oi nas parox\u00edtonas (ideia,  joia). As ox\u00edtonas mantiveram o grampinho. \u00c9 o caso de pap\u00e9is e her\u00f3i.<\/p><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;E as abelhas, atra\u00eddas pela cores vibrantes, cumprem um dos seus papeis na natureza&#8221;, escrevemos na p\u00e1g. 22. Olho vivo! A reforma ortogr\u00e1fica cassou o acento dos ditongos abertos ei e oi nas parox\u00edtonas (ideia, joia). As ox\u00edtonas mantiveram o grampinho. \u00c9 o caso de pap\u00e9is e her\u00f3i. &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-9226","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9226"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9226\/revisions"}],"predecessor-version":[{"id":9468,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9226\/revisions\/9468"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}