{"id":9202,"date":"2014-12-21T00:00:00","date_gmt":"2014-12-21T02:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/bem-vindo_a_cuba_2\/"},"modified":"2014-12-21T00:00:00","modified_gmt":"2014-12-21T02:00:00","slug":"bem-vindo_a_cuba_2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/bem-vindo_a_cuba_2\/","title":{"rendered":"Bem-vindo a Cuba 2"},"content":{"rendered":"<p><b>  <\/p>\n<p>Milagre papal<\/b>  <\/p>\n<p>Os psic\u00f3logos frisam sem se cansar: o acaso n\u00e3o existe. Se  est\u00e3o certos, n\u00e3o se deve ao destino a data do an\u00fancio da aproxima\u00e7\u00e3o Havana \u2014  Washington. Barack Obama e Ra\u00fal Castro fizeram o comunicado em 18 de dezembro. \u00c9  o dia de anivers\u00e1rio do papa Francisco. A homenagem se explica. O pont\u00edfice  mediou o acordo.    <\/p>\n<p>N\u00e3o foi f\u00e1cil. Como n\u00e3o \u00e9 f\u00e1cil a conjuga\u00e7\u00e3o do verbo que  junta cacos ou evita que cristais se quebrem. Mediar se flexiona como odiar.  Assim: <i>eu odeio (medeio), ele odeia (medeia), n\u00f3s odiamos (mediamos), eles  odeiam (medeiam). <\/i> <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> &nbsp;<\/b>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Milagre papal Os psic\u00f3logos frisam sem se cansar: o acaso n\u00e3o existe. Se est\u00e3o certos, n\u00e3o se deve ao destino a data do an\u00fancio da aproxima\u00e7\u00e3o Havana \u2014 Washington. Barack Obama e Ra\u00fal Castro fizeram o comunicado em 18 de dezembro. \u00c9 o dia de anivers\u00e1rio do papa Francisco. A homenagem se explica. O pont\u00edfice mediou o acordo. N\u00e3o foi f\u00e1cil. Como n\u00e3o \u00e9 f\u00e1cil [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9202","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9202"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9202\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}