{"id":9175,"date":"2014-03-28T12:00:00","date_gmt":"2014-03-28T15:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/por_falar_em_depor\/"},"modified":"2014-03-28T12:00:00","modified_gmt":"2014-03-28T15:00:00","slug":"por_falar_em_depor","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/por_falar_em_depor\/","title":{"rendered":"Por falar em depor&#8230;"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">      <\/p>\n<p>   <\/b> Depor \u00e9 filho de p\u00f4r e irm\u00e3ozinho dos verbos terminados em  -or. Compor, repor, transpor &amp; cia. fazem parte da fam\u00edlia pra l\u00e1 de unida.  Toda a&nbsp;mo\u00e7ada se conjuga tal qual o  paiz\u00e3o. Assim: ponho (deponho, componho, reponho, transponho), p\u00f5e (dep\u00f5e,  comp\u00f5e, rep\u00f5e, transp\u00f5e), pomos (depomos, compomos, repomos, transpomos), p\u00f5em  (dep\u00f5em, comp\u00f5em, rep\u00f5em, transp\u00f5em).   <\/p>\n<p>Moleza? Sim. T\u00e3o mole quanto andar pra frente ou tirar  pirulito de beb\u00ea. Mas h\u00e1 um tempo que d\u00e1 n\u00f3 em fuma\u00e7a. Trata-se do futuro do  subjuntivo. N\u00e3o falta quem diga ou escreva &#8220;se eu p\u00f4r&#8221;, &#8220;se ele compor&#8221;, &#8220;se n\u00f3s  repormos&#8221;. Voc\u00ea \u00e9 um deles? Bobeia. O futuro do subjuntivo se forma&nbsp;do pret\u00e9rito  perfeito menos o -am final. Assim: eu pus, ele p\u00f4s, n\u00f3s pusemos, eles  puser(am).    <\/p>\n<p>Logo: se eu puser (depuser, compuser, repuser,  transpuser), ele puser (depuser, compuser, repuser, transpuser), n\u00f3s pusermos  (depusermos, compusermos, repusermos, transpusermos), eles puserem (depuserem,  compuserem, repuserem, transpuserem).<strong> <\/strong>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depor \u00e9 filho de p\u00f4r e irm\u00e3ozinho dos verbos terminados em -or. Compor, repor, transpor &amp; cia. fazem parte da fam\u00edlia pra l\u00e1 de unida. Toda a&nbsp;mo\u00e7ada se conjuga tal qual o paiz\u00e3o. Assim: ponho (deponho, componho, reponho, transponho), p\u00f5e (dep\u00f5e, comp\u00f5e, rep\u00f5e, transp\u00f5e), pomos (depomos, compomos, repomos, transpomos), p\u00f5em (dep\u00f5em, comp\u00f5em, rep\u00f5em, transp\u00f5em). Moleza? Sim. T\u00e3o mole quanto andar pra frente ou tirar pirulito [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9175","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9175"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9175\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}