{"id":9101,"date":"2014-03-19T08:00:00","date_gmt":"2014-03-19T11:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/vexame_leso-ensino\/"},"modified":"2014-03-19T08:00:00","modified_gmt":"2014-03-19T11:00:00","slug":"vexame_leso-ensino","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/vexame_leso-ensino\/","title":{"rendered":"Vexame leso-ensino"},"content":{"rendered":"\n<div>\n<p>Valha-nos, Deus! Escola do ensino m\u00e9dio de Bras\u00edlia distribuiu uniforme pra meninada. Na  camiseta, apareceu &#8220;encino&#8221; em vez de <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">ensino<\/i>. Pais, professores,  estudantes gritaram. L\u00edderes deram entrevistas. Falaram em crime de lesa-ensino.  Ops! Esqueceram-se de pormenor pra l\u00e1 de importante. <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">Leso<\/i> \u00e9 adjetivo.  Concorda com o substantivo a que se refere: <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">crime de lesa-p\u00e1tria (p\u00e1tria  lesada), crime de lesas-autoridades (autoridades lesadas), crime de leso-ensino  (ensino lesado), crime de leso-futuro (futuro lesado), crime de lesos-leitores  (leitores lesados).<\/i>&nbsp; <strong><\/strong>  <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Valha-nos, Deus! Escola do ensino m\u00e9dio de Bras\u00edlia distribuiu uniforme pra meninada. Na camiseta, apareceu &#8220;encino&#8221; em vez de ensino. Pais, professores, estudantes gritaram. L\u00edderes deram entrevistas. Falaram em crime de lesa-ensino. Ops! Esqueceram-se de pormenor pra l\u00e1 de importante. Leso \u00e9 adjetivo. Concorda com o substantivo a que se refere: crime de lesa-p\u00e1tria (p\u00e1tria lesada), crime de lesas-autoridades (autoridades lesadas), crime de leso-ensino (ensino [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9101","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9101"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9101\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}