{"id":9097,"date":"2014-12-09T11:00:00","date_gmt":"2014-12-09T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/marcelo_abreu_comenta\/"},"modified":"2014-12-09T11:00:00","modified_gmt":"2014-12-09T13:00:00","slug":"marcelo_abreu_comenta","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/marcelo_abreu_comenta\/","title":{"rendered":"Marcelo Abreu comenta"},"content":{"rendered":"\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">TV ligada num restaurante aqui do Sudoeste. Passa um  telejornal local. Rep\u00f3rter (o mo\u00e7o \u00e9 at\u00e9 experiente \u2014 pelo menos est\u00e1 na estrada  faz tempo), narra uma persegui\u00e7\u00e3o policial. E dispara, ao vivo, imponente \u00e0  c\u00e2mera: &#8220;Os policiais come\u00e7aram a agirem&#8221;.  <\/p>\n<p>Ent\u00e3o, t\u00e1!  <\/p>\n<p><b>  <\/p>\n<p><\/b>  <\/p>\n<p>N\u00e3o t\u00e1, Marcelo. Locu\u00e7\u00f5es verbais adotam a lei do menor esfor\u00e7o. Se  um verbo d\u00e1 o recado, o outro fica no bem-bom. No caso, o auxiliar se flexiona.  O principal fica no infinitivo: <i>Os policiais come\u00e7aram a agir. Os garotos v\u00e3o  chegar juntos. <\/i><\/div>\n<div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TV ligada num restaurante aqui do Sudoeste. Passa um telejornal local. Rep\u00f3rter (o mo\u00e7o \u00e9 at\u00e9 experiente \u2014 pelo menos est\u00e1 na estrada faz tempo), narra uma persegui\u00e7\u00e3o policial. E dispara, ao vivo, imponente \u00e0 c\u00e2mera: &#8220;Os policiais come\u00e7aram a agirem&#8221;. Ent\u00e3o, t\u00e1! N\u00e3o t\u00e1, Marcelo. Locu\u00e7\u00f5es verbais adotam a lei do menor esfor\u00e7o. Se um verbo d\u00e1 o recado, o outro fica no bem-bom. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9097","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9097"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9097\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}