{"id":9070,"date":"2014-08-11T10:40:00","date_gmt":"2014-08-11T13:40:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-216\/"},"modified":"2015-11-13T10:17:49","modified_gmt":"2015-11-13T12:17:49","slug":"leitor_pergunta-216","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-216\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"<p><b>    <\/p>\n<p> <\/b> Por ora? Por hora? Como distinguir uma forma da outra?  (Clarice Bonfim)<i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p>Por hora, Clarice, significa <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">a cada 60 minutos<\/i>: A velocidade \u00e9  de 60km por hora. Ganho R$ 50 por hora de  trabalho. <\/i><i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p>Por ora quer dizer <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">por enquanto, por agora<\/i>: Por ora, a  velocidade da via \u00e9 de 60km por hora. O governo n\u00e3o pretende, por ora, editar  nova medida provis\u00f3ria.<\/i><i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><\/i> <\/p>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n<div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por ora? Por hora? Como distinguir uma forma da outra? (Clarice Bonfim) Por hora, Clarice, significa a cada 60 minutos: A velocidade \u00e9 de 60km por hora. Ganho R$ 50 por hora de trabalho. Por ora quer dizer por enquanto, por agora: Por ora, a velocidade da via \u00e9 de 60km por hora. O governo n\u00e3o pretende, por ora, editar nova medida provis\u00f3ria. &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-9070","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9070"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9070\/revisions"}],"predecessor-version":[{"id":11220,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9070\/revisions\/11220"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}