{"id":9007,"date":"2014-03-08T00:00:00","date_gmt":"2014-03-08T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/diquinhas_infantis_8\/"},"modified":"2015-11-12T19:36:23","modified_gmt":"2015-11-12T21:36:23","slug":"diquinhas_infantis_8","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/diquinhas_infantis_8\/","title":{"rendered":"Diquinhas infantis 8"},"content":{"rendered":"<div> <strong> <\/p>\n<p><\/strong><strong>Eva, a primeirona<\/strong>  <\/p>\n<p>Ad\u00e3o nasceu. Foi o primeiro ser humano da Terra. Deus o  moldou do barro. Com um sopro, lhe deu vida. O tempo passou. Sem companhia de  semelhantes, o morador do \u00c9den se sentia s\u00f3, muito s\u00f3. N\u00e3o tinha com quem  conversar, nem passear, nem trocar ideias.  <\/p>\n<p>O Senhor sentiu pena do primog\u00eanito. Decidiu criar uma  mulher. Ela seria mais evolu\u00edda que o antecedente. Em vez de vir do barro,  nasceria de um humano. Uma costela de Ad\u00e3o originou Eva. Al\u00e9m de linda e  sedutora, ela era muito curiosa. Gostava de aprender. Por isso comeu o fruto  proibido. Era o fruto do conhecimento.<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><i>  <\/p>\n<p>B\u00edblia<\/i><\/b>  <\/p>\n<p>A hist\u00f3ria de Ad\u00e3o e Eva est\u00e1 na <i>B\u00edblia<\/i>. O livro  <i>G\u00eaneses <\/i>fala da origem do mundo. Vale a pena dar uma olhada na obra. \u00c9  cheia de aventuras. Pra l\u00e1 de legal.<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p>Minoria<\/b>  <\/p>\n<p>Sabia? O portugu\u00eas tem pouquinhas palavras terminadas com n.  Uma delas \u00e9 \u00c9den. Outras s\u00e3o abd\u00f4men, p\u00f3len, h\u00edfen.  <strong> <\/p>\n<p><\/strong><strong>Armadilha<\/strong>  <\/p>\n<p>As palavras terminadas em <b>n<\/b> adoram pregar pe\u00e7as. No  singular, elas t\u00eam acento. No plural, n\u00e3o t\u00eam. Veja s\u00f3:   <\/p>\n<p>\u00e9den \u2014 edens abd\u00f4men \u2014 abdomens p\u00f3len \u2014 polens h\u00edfen \u2014 hifens<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p>Agora voc\u00ea<\/b>  <\/p>\n<p>Escreva o plural de el\u00e9tron. N\u00e3o caia na cilada. Olho no  acento:&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;. &nbsp;<b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p><\/b><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Eva, a primeirona Ad\u00e3o nasceu. Foi o primeiro ser humano da Terra. Deus o moldou do barro. Com um sopro, lhe deu vida. O tempo passou. Sem companhia de semelhantes, o morador do \u00c9den se sentia s\u00f3, muito s\u00f3. N\u00e3o tinha com quem conversar, nem passear, nem trocar ideias. O Senhor sentiu pena do primog\u00eanito. Decidiu criar uma mulher. Ela seria mais evolu\u00edda que o [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62,1],"tags":[],"class_list":["post-9007","post","type-post","status-publish","format-standard","hentry","category-diquinhas","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=9007"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9007\/revisions"}],"predecessor-version":[{"id":11181,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/9007\/revisions\/11181"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=9007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=9007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=9007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}