{"id":8941,"date":"2014-07-25T16:00:00","date_gmt":"2014-07-25T19:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1191\/"},"modified":"2015-11-12T12:45:31","modified_gmt":"2015-11-12T14:45:31","slug":"erramos-1191","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1191\/","title":{"rendered":"Erramos"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>&#8220;Com essa passagem bonita&#8221;, disse Ana, &#8220;O c\u00e9u est\u00e1 em festa&#8221;, escrevemos na  capa. Ops! A continua\u00e7\u00e3o do per\u00edodo exige letra min\u00fascula. Assim: &#8220;Com essa  passagem bonita&#8221;, disse Ana, &#8220;o c\u00e9u est\u00e1 em  festa.&#8221;<\/p><\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Com essa passagem bonita&#8221;, disse Ana, &#8220;O c\u00e9u est\u00e1 em festa&#8221;, escrevemos na capa. Ops! A continua\u00e7\u00e3o do per\u00edodo exige letra min\u00fascula. Assim: &#8220;Com essa passagem bonita&#8221;, disse Ana, &#8220;o c\u00e9u est\u00e1 em festa.&#8221; &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-8941","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8941"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8941\/revisions"}],"predecessor-version":[{"id":9558,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8941\/revisions\/9558"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}