{"id":8917,"date":"2014-02-25T11:30:00","date_gmt":"2014-02-25T14:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/pergunta_de_leitor-5\/"},"modified":"2015-11-13T10:25:16","modified_gmt":"2015-11-13T12:25:16","slug":"pergunta_de_leitor-5","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/pergunta_de_leitor-5\/","title":{"rendered":"Pergunta de leitor"},"content":{"rendered":"<p><b> <\/b>  <\/p>\n<p>Estamos com d\u00favida na seguinte frase: &#8220;Miss\u00f5es se fazem com os p\u00e9s dos que v\u00e3o com os  joelhos dos que oram e com as m\u00e3os dos que contribuem&#8221;. Por favor, nos ajude!  Est\u00e1 correta ou n\u00e3o?(Jos\u00e9 e sua turma) <\/p>\n<p><b>  <\/p>\n<p><\/b> Mo\u00e7ada, cad\u00ea a v\u00edrgula? O sinalzinho separa as ora\u00e7\u00f5es  coordenadas. Assim: <i>Miss\u00f5es se fazem com os p\u00e9s dos que v\u00e3o, com os joelhos  dos que oram e com as m\u00e3os dos que  contribuem<\/i>.  <\/p>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estamos com d\u00favida na seguinte frase: &#8220;Miss\u00f5es se fazem com os p\u00e9s dos que v\u00e3o com os joelhos dos que oram e com as m\u00e3os dos que contribuem&#8221;. Por favor, nos ajude! Est\u00e1 correta ou n\u00e3o?(Jos\u00e9 e sua turma) Mo\u00e7ada, cad\u00ea a v\u00edrgula? O sinalzinho separa as ora\u00e7\u00f5es coordenadas. Assim: Miss\u00f5es se fazem com os p\u00e9s dos que v\u00e3o, com os joelhos dos que oram [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-8917","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8917"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8917\/revisions"}],"predecessor-version":[{"id":11442,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8917\/revisions\/11442"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}