{"id":8908,"date":"2014-02-25T10:00:00","date_gmt":"2014-02-25T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/dupla_da_pesada\/"},"modified":"2014-02-25T10:00:00","modified_gmt":"2014-02-25T13:00:00","slug":"dupla_da_pesada","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/dupla_da_pesada\/","title":{"rendered":"Dupla da pesada"},"content":{"rendered":"\n<div><b>  <\/p>\n<p><\/b><i> <\/i><i>Todo<\/i> forma outra dupla da  pesada. Trata-se de todo-poderoso. O todo, no caso, equivale a  totalmente. Altivo, n\u00e3o se flexiona nem a pedido de Momo. Masculino ou  feminino, singular ou plural, \u00e9 tudo igual: Ele \u00e9 todo-poderoso. Ela,  todo-poderosa. Eles, todo-poderosos. Elas, todo-poderosas.<b><\/b><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Todo forma outra dupla da pesada. Trata-se de todo-poderoso. O todo, no caso, equivale a totalmente. Altivo, n\u00e3o se flexiona nem a pedido de Momo. Masculino ou feminino, singular ou plural, \u00e9 tudo igual: Ele \u00e9 todo-poderoso. Ela, todo-poderosa. Eles, todo-poderosos. Elas, todo-poderosas.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8908","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8908"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8908\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}