{"id":8903,"date":"2014-07-22T17:30:00","date_gmt":"2014-07-22T20:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1184\/"},"modified":"2015-11-12T12:45:33","modified_gmt":"2015-11-12T14:45:33","slug":"erramos-1184","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1184\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<div>\n<p>&#8220;O mundo \u00e1rabe, como o  conhecemos, est\u00e1 desabando. A essa altura, o que Washington pode fazer \u00e9 apenas  se preparar para o que vir\u00e1 depois&#8221;, escrevemos na p\u00e1g. 12. Falamos de tempo  presente, n\u00e3o? O <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">este<\/i> pede passagem. Assim: <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">O mundo \u00e1rabe, como o  conhecemos, est\u00e1 desabando. A esta altura, o que Washington pode fazer \u00e9 apenas  se preparar para o que vir\u00e1 depois.<\/i><\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O mundo \u00e1rabe, como o conhecemos, est\u00e1 desabando. A essa altura, o que Washington pode fazer \u00e9 apenas se preparar para o que vir\u00e1 depois&#8221;, escrevemos na p\u00e1g. 12. Falamos de tempo presente, n\u00e3o? O este pede passagem. Assim: O mundo \u00e1rabe, como o conhecemos, est\u00e1 desabando. A esta altura, o que Washington pode fazer \u00e9 apenas se preparar para o que vir\u00e1 depois. &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-8903","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8903"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8903\/revisions"}],"predecessor-version":[{"id":9561,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8903\/revisions\/9561"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}