{"id":8902,"date":"2014-02-24T15:30:00","date_gmt":"2014-02-24T18:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos_2-8\/"},"modified":"2015-11-12T12:48:39","modified_gmt":"2015-11-12T14:48:39","slug":"erramos_2-8","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos_2-8\/","title":{"rendered":"Erramos 2"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>&#8220;Em caso de a aprova\u00e7\u00e3o do governador despencar, n\u00e3o sei se haver\u00e1 condi\u00e7\u00f5es  <b>do<\/b> partido manter o nome do Agnelo&#8221;, escrevemos na p\u00e1g. 20. Ops!  Esquecemos pormenor pra l\u00e1 de importante. O sujeito sofre de alergia. N\u00e3o  suporta preposi\u00e7\u00e3o. Com a dupla, \u00e9 um l\u00e1 e outro c\u00e1. Assim: \u2026 n\u00e3o sei se haver\u00e1  condi\u00e7\u00f5es <b style=\"font-style: italic\">de o<\/b> partido manter o nome do Agnelo. <\/div>\n<div>&nbsp; <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Em caso de a aprova\u00e7\u00e3o do governador despencar, n\u00e3o sei se haver\u00e1 condi\u00e7\u00f5es do partido manter o nome do Agnelo&#8221;, escrevemos na p\u00e1g. 20. Ops! Esquecemos pormenor pra l\u00e1 de importante. O sujeito sofre de alergia. N\u00e3o suporta preposi\u00e7\u00e3o. Com a dupla, \u00e9 um l\u00e1 e outro c\u00e1. Assim: \u2026 n\u00e3o sei se haver\u00e1 condi\u00e7\u00f5es de o partido manter o nome do Agnelo. &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-8902","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8902"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8902\/revisions"}],"predecessor-version":[{"id":9637,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8902\/revisions\/9637"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}