{"id":8898,"date":"2014-02-24T08:00:00","date_gmt":"2014-02-24T11:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cochilos_da_revisao-65\/"},"modified":"2014-02-24T08:00:00","modified_gmt":"2014-02-24T11:00:00","slug":"cochilos_da_revisao-65","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cochilos_da_revisao-65\/","title":{"rendered":"Cochilos da revis\u00e3o"},"content":{"rendered":"<div>\n<p>Flat\u00f4nio Jos\u00e9 da Silva<br style=\"font-style: italic;font-family: Verdana,Arial,Helvetica,sans-serif\"><br style=\"font-style: italic;font-family: Verdana,Arial,Helvetica,sans-serif\">&#8220;Num passado recente, <strong style=\"font-style: italic;font-family: Verdana,Arial,Helvetica,sans-serif\">corrigiu-se<\/strong> algumas distor\u00e7\u00f5es relacionadas ao  pagamento de pens\u00e3o a filhas de militares&#8221;. <\/div>\n<div style=\"font-style: italic;font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Corrigindo: Num passado recente, <strong>corrigiram-se<\/strong>&nbsp;algumas distor\u00e7\u00f5es relacionadas ao  pagamento de pens\u00e3o a filhas de militares. <\/div>\n<div style=\"font-style: italic;font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Explica\u00e7\u00e3o &#8211; Erro de concord\u00e2ncia: o sujeito passivo no plural (algumas  distor\u00e7\u00f5es) exige o verbo (sempre transitivo direto) igualmente no plural  (corrigiram-se). Observe que se trata de voz passiva sint\u00e9tica (com o pronome  apassivador &#8220;se&#8221;). Na&nbsp;voz passiva anal\u00edtica (com o verbo &#8220;ser&#8221;), a frase fica  assim: Num passado recente, foram corrigidas algumas distor\u00e7\u00f5es relacionadas  ao pagamento de pens\u00e3o a filhas de militares. <\/p><\/div>\n<div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Flat\u00f4nio Jos\u00e9 da Silva&#8220;Num passado recente, corrigiu-se algumas distor\u00e7\u00f5es relacionadas ao pagamento de pens\u00e3o a filhas de militares&#8221;. Corrigindo: Num passado recente, corrigiram-se&nbsp;algumas distor\u00e7\u00f5es relacionadas ao pagamento de pens\u00e3o a filhas de militares. Explica\u00e7\u00e3o &#8211; Erro de concord\u00e2ncia: o sujeito passivo no plural (algumas distor\u00e7\u00f5es) exige o verbo (sempre transitivo direto) igualmente no plural (corrigiram-se). Observe que se trata de voz passiva sint\u00e9tica (com o [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8898","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8898"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8898\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}