{"id":8785,"date":"2014-07-14T10:00:00","date_gmt":"2014-07-14T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/manoel_de_barros_confessa\/"},"modified":"2014-07-14T10:00:00","modified_gmt":"2014-07-14T13:00:00","slug":"manoel_de_barros_confessa","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/manoel_de_barros_confessa\/","title":{"rendered":"Manoel de Barros confessa"},"content":{"rendered":"<p><b>  <\/p>\n<p><\/b> &#8220;Uso a palavra para compor meus sil\u00eancios.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Uso a palavra para compor meus sil\u00eancios.&#8221;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8785","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8785"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8785\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}