{"id":8755,"date":"2014-07-10T00:00:00","date_gmt":"2014-07-10T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-197\/"},"modified":"2015-11-13T10:17:55","modified_gmt":"2015-11-13T12:17:55","slug":"leitor_pergunta-197","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-197\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"\n<p>O   jornal Estado de Minas, no Caderno Cultura, publicou a seguinte   manchete: &#8220;Inhotim bate recorde de p\u00fablico com a Copa do Mundo, e   estrangeiros s\u00e3o maioria entre os visitantes&#8221;. Estrangeiros s\u00e3o   &#8220;maioria&#8221; ou &#8220;maiorias&#8221;? O portal do Globo foi em sentido diverso: As   mulheres s\u00e3o maiorias entre os consumidores que rodam as lojas de   Madureira&#8221;. E da\u00ed? Estou com n\u00f3 nos miolos. <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   (Carlos Ferreira)<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">     <\/p>\n<p>O   singular merece nota 10. O plural n\u00e3o est\u00e1 com nada. Por qu\u00ea? Fica no   singular o substantivo abstrato que, depois de verbo de liga\u00e7\u00e3o (ser,   estar, tornar-se, virar), caracterize genericamente o sujeito plural: Os   jovens s\u00e3o alvo de campanhas publicit\u00e1rias. Filmes nacionais foram   destaque do Festival de Bras\u00edlia. O sujeito e o predicado s\u00e3o parte da   ora\u00e7\u00e3o. Estrangeiros s\u00e3o maioria entre os visitantes. As mulheres s\u00e3o   maioria entre os consumidores.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O jornal Estado de Minas, no Caderno Cultura, publicou a seguinte manchete: &#8220;Inhotim bate recorde de p\u00fablico com a Copa do Mundo, e estrangeiros s\u00e3o maioria entre os visitantes&#8221;. Estrangeiros s\u00e3o &#8220;maioria&#8221; ou &#8220;maiorias&#8221;? O portal do Globo foi em sentido diverso: As mulheres s\u00e3o maiorias entre os consumidores que rodam as lojas de Madureira&#8221;. E da\u00ed? Estou com n\u00f3 nos miolos. (Carlos Ferreira) O [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-8755","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8755"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8755\/revisions"}],"predecessor-version":[{"id":11230,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8755\/revisions\/11230"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}