{"id":8656,"date":"2013-08-14T08:35:00","date_gmt":"2013-08-14T11:35:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/quem_da_mais-2\/"},"modified":"2013-08-14T08:35:00","modified_gmt":"2013-08-14T11:35:00","slug":"quem_da_mais-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/quem_da_mais-2\/","title":{"rendered":"Quem d\u00e1 mais?"},"content":{"rendered":"\n<p>   &#8220;Cada dia com a sua agonia&#8221;, diz o povo sabido. Certo?  Certo. Mas n\u00e3o universal. Algumas torturas t\u00eam vida mais longa. \u00c9 o caso do  trem-bala. Desde 2009, a concorr\u00eancia para o projeto entrou no jogo do empurra.  O terceiro adiamento foi anunciado na ter\u00e7a. N\u00e3o deu outra. A palavra    leil\u00e3o ganhou manchetes. Pintou, ent\u00e3o, a curiosidade. De onde veio o  voc\u00e1bulo?    <\/p>\n<p>Os dicion\u00e1rios de etimologia respondem. A diss\u00edlaba nasceu  \u00e1rabe. Na l\u00edngua de Kalil Gibram, al-\u00e3\u00b4l\u00e3m quer dizer venda p\u00fablica. Na  de Cam\u00f5es, tamb\u00e9m. &#8220;Quem d\u00e1 mais?&#8221;, pergunta o leiloeiro. A provoca\u00e7\u00e3o segue at\u00e9  a batida do martelo. Leva o objeto quem bota a m\u00e3o mais fundo no bolso. Em bom  portugu\u00eas: quem d\u00e1 o lance mais alto. <b> &nbsp;<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Cada dia com a sua agonia&#8221;, diz o povo sabido. Certo? Certo. Mas n\u00e3o universal. Algumas torturas t\u00eam vida mais longa. \u00c9 o caso do trem-bala. Desde 2009, a concorr\u00eancia para o projeto entrou no jogo do empurra. O terceiro adiamento foi anunciado na ter\u00e7a. N\u00e3o deu outra. A palavra leil\u00e3o ganhou manchetes. Pintou, ent\u00e3o, a curiosidade. De onde veio o voc\u00e1bulo? Os dicion\u00e1rios de [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8656","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8656"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8656\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}