{"id":8637,"date":"2014-10-21T11:00:00","date_gmt":"2014-10-21T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_proibido\/"},"modified":"2014-10-21T11:00:00","modified_gmt":"2014-10-21T13:00:00","slug":"e_proibido","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_proibido\/","title":{"rendered":"\u00c9 proibido"},"content":{"rendered":"<p><b><\/b>  <\/p>\n<p>Hoje, quando li o t\u00edtulo &#8220;\u00c9 proibida venda de creme que promete reduzir  gordura&#8221;, fiquei chocada. N\u00e3o com a not\u00edcia, mas com o portugu\u00eas. Aprendi que,  se o substantivo n\u00e3o vem acompanhado de artigo, o <i>proibido<\/i> n\u00e3o varia. Mas  l\u00e1 estava o feminino. Estou errada? (Moema)  <\/p>\n<p>*  <\/p>\n<p>Voc\u00ea est\u00e1 cert\u00edssima, Moema. O jornal  tinha duas possibilidades. Uma: \u00c9 proibido entrada. A outra: \u00c9 proibida a  entrada. A regra vale para outros adjetivos: <i>\u00c1gua \u00e9 bom pra sa\u00fade. A \u00e1gua \u00e9  boa pra sa\u00fade. Dois quilos \u00e9 suficiente pra preparar o prato. Os dois quilos s\u00e3o  suficientes pra preparar o quarto. \u00c9 necess\u00e1rio volunt\u00e1rios. S\u00e3o necess\u00e1rios os  volunt\u00e1rios.<\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje, quando li o t\u00edtulo &#8220;\u00c9 proibida venda de creme que promete reduzir gordura&#8221;, fiquei chocada. N\u00e3o com a not\u00edcia, mas com o portugu\u00eas. Aprendi que, se o substantivo n\u00e3o vem acompanhado de artigo, o proibido n\u00e3o varia. Mas l\u00e1 estava o feminino. Estou errada? (Moema) * Voc\u00ea est\u00e1 cert\u00edssima, Moema. O jornal tinha duas possibilidades. Uma: \u00c9 proibido entrada. A outra: \u00c9 proibida a [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8637","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8637"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8637\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}