{"id":8632,"date":"2014-10-20T15:00:00","date_gmt":"2014-10-20T17:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1133\/"},"modified":"2015-11-12T12:45:09","modified_gmt":"2015-11-12T14:45:09","slug":"erramos-1133","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1133\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>&#8220;Fundado em 1978, o  Parque da Cidade recebe milhares de brasilienses diariamente. Nesse tempo de  calor, a sombra das \u00e1rvores \u00e9 um convite ao descanso&#8221;, escrevemos na p\u00e1g. 21.  Ops! Trocamos o pronome e abusamos do artigo indefinido. Cortemos o excesso e  substituamos <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">esse<\/i> por <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">este<\/i>, que indica tempo presente. Assim:  <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">Neste tempo de calor, a sombra das \u00e1rvores \u00e9 convite ao  descanso.<\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Fundado em 1978, o Parque da Cidade recebe milhares de brasilienses diariamente. Nesse tempo de calor, a sombra das \u00e1rvores \u00e9 um convite ao descanso&#8221;, escrevemos na p\u00e1g. 21. Ops! Trocamos o pronome e abusamos do artigo indefinido. Cortemos o excesso e substituamos esse por este, que indica tempo presente. Assim: Neste tempo de calor, a sombra das \u00e1rvores \u00e9 convite ao descanso.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-8632","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8632"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8632\/revisions"}],"predecessor-version":[{"id":9508,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8632\/revisions\/9508"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}