{"id":8620,"date":"2014-01-31T16:00:00","date_gmt":"2014-01-31T18:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1132\/"},"modified":"2015-11-12T12:48:51","modified_gmt":"2015-11-12T14:48:51","slug":"erramos-1132-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1132-2\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>&#8220;O Livro dos Esp\u00edritos, O Livro dos M\u00e9diuns, O  C\u00e9u e o Inferno, A G\u00eanese, Obras P\u00f3stumas&#8221;, escrevemos na p\u00e1g. 11. Ops! Nome de  livro&nbsp;n\u00e3o tem pedigree.&nbsp;Escreve-se em it\u00e1lico s\u00f3 com a inicial mai\u00fascula.  Melhor: <i>O livro dos esp\u00edritos, O livro dos m\u00e9diuns, O c\u00e9u e o inferno, A  g\u00eanese, Obras p\u00f3stumas.<\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O Livro dos Esp\u00edritos, O Livro dos M\u00e9diuns, O C\u00e9u e o Inferno, A G\u00eanese, Obras P\u00f3stumas&#8221;, escrevemos na p\u00e1g. 11. Ops! Nome de livro&nbsp;n\u00e3o tem pedigree.&nbsp;Escreve-se em it\u00e1lico s\u00f3 com a inicial mai\u00fascula. Melhor: O livro dos esp\u00edritos, O livro dos m\u00e9diuns, O c\u00e9u e o inferno, A g\u00eanese, Obras p\u00f3stumas.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-8620","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8620"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8620\/revisions"}],"predecessor-version":[{"id":9652,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8620\/revisions\/9652"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}