{"id":8584,"date":"2014-10-17T06:00:00","date_gmt":"2014-10-17T09:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_vedete_da_eleicao_3\/"},"modified":"2014-10-17T06:00:00","modified_gmt":"2014-10-17T09:00:00","slug":"a_vedete_da_eleicao_3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a_vedete_da_eleicao_3\/","title":{"rendered":"A vedete da elei\u00e7\u00e3o 3"},"content":{"rendered":"<p><b> <\/p>\n<p>Ciladas<\/b>  <\/p>\n<p>Olho vivo! As palavras adoram pegar o bobo na casca do ovo.  Basta um descuido e\u2026 adeus, nota 10. Aten\u00e7\u00e3o plena se imp\u00f5e. O sufixo -ar tem de  se colar ao s ou ao z do radical. Se n\u00e3o for poss\u00edvel, ele  precisar\u00e1 de ponte. A\u00ed, cessa tudo o que a musa antiga canta.  Compare:    <\/p>\n<p>pesqui<b>s<\/b>a \u2014 pesqui<strong>s<\/strong>ar   cami<strong>s<\/strong>a \u2014  encami<strong>s<\/strong>ar  <i style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> jui<strong>z<\/strong> \u2014 ajui<strong>z<\/strong>ar rai<strong>z<\/strong> \u2014 enrai<strong>z<\/strong>ar  <\/p>\n<p>Viu? O sufixo -ar se cola ao s do radical. Veja outro  caso:  <\/p>\n<p>cateque<b>s<\/b>e \u2014 catequizar<\/i>  <\/p>\n<p>O -ar n\u00e3o se cola ao radical. Caso se colasse, ter\u00edamos  &#8220;catequesar&#8221;. Nada feito. Entra em cartaz o sufixo -izar \u2014 escrito sempre,  sempre mesmo, com z &nbsp;(canalizar, avalizar, civilizar).  <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> &nbsp;<\/b>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciladas Olho vivo! As palavras adoram pegar o bobo na casca do ovo. Basta um descuido e\u2026 adeus, nota 10. Aten\u00e7\u00e3o plena se imp\u00f5e. O sufixo -ar tem de se colar ao s ou ao z do radical. Se n\u00e3o for poss\u00edvel, ele precisar\u00e1 de ponte. A\u00ed, cessa tudo o que a musa antiga canta. Compare: pesquisa \u2014 pesquisar camisa \u2014 encamisar juiz \u2014 ajuizar [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8584","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8584"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8584\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}