{"id":8582,"date":"2013-04-18T08:05:00","date_gmt":"2013-04-18T11:05:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-190\/"},"modified":"2015-11-13T10:21:04","modified_gmt":"2015-11-13T12:21:04","slug":"leitor_pergunta-190","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-190\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"<p><b> <\/p>\n<p> <\/b> Gostaria de saber se h\u00e1 pleonasmo no lema do governo  federal: &#8220;Brasil, pa\u00eds rico \u00e9 pa\u00eds sem pobreza&#8221;.(Pedro Jhemyson) <\/p>\n<p><b>  <\/p>\n<p><\/b> H\u00e1  pa\u00edses ricos com povo pobre. O Brasil serve de exemplo.  Na ditadura,  os militares diziam que precisavam deixar o bolo crescer para ent\u00e3o   incluir a popula\u00e7\u00e3o. O Tesouro nadava em riqueza. Mas boa parte dos  brasileiros  afundava na mis\u00e9ria. Dilma joga no time contr\u00e1rio. Afirma  que um pa\u00eds s\u00f3 \u00e9 rico  se o povo tamb\u00e9m for. Inspira-se talvez na  Dinamarca, Su\u00e9cia, Noruega.&nbsp;Chegar\u00e1 l\u00e1?  <\/p>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gostaria de saber se h\u00e1 pleonasmo no lema do governo federal: &#8220;Brasil, pa\u00eds rico \u00e9 pa\u00eds sem pobreza&#8221;.(Pedro Jhemyson) H\u00e1 pa\u00edses ricos com povo pobre. O Brasil serve de exemplo. Na ditadura, os militares diziam que precisavam deixar o bolo crescer para ent\u00e3o incluir a popula\u00e7\u00e3o. O Tesouro nadava em riqueza. Mas boa parte dos brasileiros afundava na mis\u00e9ria. Dilma joga no time contr\u00e1rio. Afirma [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-8582","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8582"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8582\/revisions"}],"predecessor-version":[{"id":11316,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8582\/revisions\/11316"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}