{"id":8571,"date":"2013-08-09T12:00:00","date_gmt":"2013-08-09T15:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ontem_e_hoje\/"},"modified":"2013-08-09T12:00:00","modified_gmt":"2013-08-09T15:00:00","slug":"ontem_e_hoje","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ontem_e_hoje\/","title":{"rendered":"Ontem e hoje"},"content":{"rendered":"<p><b> <\/b>  <\/p>\n<p>No s\u00e9culo 16, o padre Ant\u00f4nio Vieira se revelou cidad\u00e3o  sintonizado com os costumes da \u00e9poca em que viveu. \u00c9 dele esta passagem: &#8220;A  mulher s\u00f3 deve sair de casa em tr\u00eas ocasi\u00f5es: no batismo, no casamento e no  enterro&#8221;.   <\/p>\n<p>Lin Yutang, mais de 400 anos depois, retratou os tempos  modernos: &#8220;As mulheres s\u00e3o seres humanos exatamente como os homens \u2014 iguais na  capacidade de julgar e de cometer erros se lhes derdes a mesma experi\u00eancia do  mundo e os mesmos contatos; na capacidade de realizar trabalho eficaz, de  conservar a cabe\u00e7a fresca se lhes derdes o mesmo treino nos neg\u00f3cios; no  descortino social se n\u00e3o as trancardes em casa; e, finalmente, na capacidade de  governar, pois, se as mulheres governassem o mundo, n\u00e3o poderiam talvez  estabelecer maior confus\u00e3o nele do que o fizeram os homens&#8221;.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>No s\u00e9culo 16, o padre Ant\u00f4nio Vieira se revelou cidad\u00e3o sintonizado com os costumes da \u00e9poca em que viveu. \u00c9 dele esta passagem: &#8220;A mulher s\u00f3 deve sair de casa em tr\u00eas ocasi\u00f5es: no batismo, no casamento e no enterro&#8221;. Lin Yutang, mais de 400 anos depois, retratou os tempos modernos: &#8220;As mulheres s\u00e3o seres humanos exatamente como os homens \u2014 iguais na capacidade de [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8571","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8571"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8571\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}