{"id":8558,"date":"2013-08-08T13:30:00","date_gmt":"2013-08-08T16:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/tres_historinhas_\/"},"modified":"2013-08-08T13:30:00","modified_gmt":"2013-08-08T16:30:00","slug":"tres_historinhas_","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/tres_historinhas_\/","title":{"rendered":"Tr\u00eas historinhas"},"content":{"rendered":"\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<div>\n<div>\n<div> <b>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/b> <\/div>\n<\/p><\/div>\n<div>\n<div> Tr\u00eas coisas que n\u00e3o podem faltar : <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<div>\n<div>\n<div>\n<div> &nbsp; <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<div>\n<div>\n<div>\n<div> 1. Certa  vez, o povo de uma vilarejo decidiu se reunir no centro do lugar para  orar a Deus pedindo por chuvas&#8230;Mas apenas um garoto trouxe  guarda-chuva. Isso<i> \u00e9&nbsp;<\/i>F\u00c9!&nbsp;   <\/p>\n<p> 2. Quando voc\u00ea joga um beb\u00ea de 1 ano de idade para o alto, ele gargalha porque sabe que na queda algu\u00e9m vai segur\u00e1-lo. Isso \u00e9 &nbsp; &nbsp;&nbsp; CONFIAN\u00c7A! <\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<div>\n<div>\n<p> 3. A  cada noite, antes de dormir, n\u00e3o temos garantia nenhuma de que  estaremos vivos na manh\u00e3 seguinte, mas, ainda assim, colocamos o  despertador para tocar. Isso \u00e9<i> &nbsp; &nbsp; <\/i>ESPERAN\u00c7A!&nbsp;&nbsp; <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<div>\n<div> &nbsp; <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<div>\n<div> <b>&nbsp;<\/b>Ent\u00e3o, que nunca lhe falte:<b> <\/b>f\u00e9, confian\u00e7a e esperan\u00e7a. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; <b><\/b><\/div>\n<\/div>\n<div>\n<div>   <b>&nbsp;<\/b>(Colabora\u00e7\u00e3o Maria Abadia Alves)   <\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n<div>\n<div> &nbsp; <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Tr\u00eas coisas que n\u00e3o podem faltar : &nbsp; 1. Certa vez, o povo de uma vilarejo decidiu se reunir no centro do lugar para orar a Deus pedindo por chuvas&#8230;Mas apenas um garoto trouxe guarda-chuva. Isso \u00e9&nbsp;F\u00c9!&nbsp; 2. Quando voc\u00ea joga um beb\u00ea de 1 ano de idade para o alto, ele gargalha porque sabe que na queda algu\u00e9m vai segur\u00e1-lo. Isso \u00e9 &nbsp; [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8558","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8558"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8558\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}