{"id":8512,"date":"2013-08-05T17:00:00","date_gmt":"2013-08-05T20:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1109\/"},"modified":"2015-11-12T15:14:36","modified_gmt":"2015-11-12T17:14:36","slug":"erramos-1109","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1109\/","title":{"rendered":"Erramos"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>&#8220;Toda a programa\u00e7\u00e3o, nos outros dias da semana,  musical ser\u00e1 desenvolvida no local&#8221;, escrevemos na p\u00e1g. 4. N\u00e3o deu pra entender,  n\u00e3o \u00e9? Termos se deslocaram e desestruturaram o per\u00edodo. Que tal retornar ao  galho? Talvez assim: Toda a programa\u00e7\u00e3o musical, nos outros dias da semana,  ser\u00e1 desenvolvida no local. Ou assim:  Toda a programa\u00e7\u00e3o, nos outros dias da semana musical, ser\u00e1 desenvolvida no  local.<\/p><\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Toda a programa\u00e7\u00e3o, nos outros dias da semana, musical ser\u00e1 desenvolvida no local&#8221;, escrevemos na p\u00e1g. 4. N\u00e3o deu pra entender, n\u00e3o \u00e9? Termos se deslocaram e desestruturaram o per\u00edodo. Que tal retornar ao galho? Talvez assim: Toda a programa\u00e7\u00e3o musical, nos outros dias da semana, ser\u00e1 desenvolvida no local. Ou assim: Toda a programa\u00e7\u00e3o, nos outros dias da semana musical, ser\u00e1 desenvolvida no local. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-8512","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8512"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8512\/revisions"}],"predecessor-version":[{"id":9751,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8512\/revisions\/9751"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}