{"id":8499,"date":"2013-12-31T09:30:00","date_gmt":"2013-12-31T11:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/oto_lara_resende_escreveu-2\/"},"modified":"2013-12-31T09:30:00","modified_gmt":"2013-12-31T11:30:00","slug":"oto_lara_resende_escreveu-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/oto_lara_resende_escreveu-2\/","title":{"rendered":"Oto Lara Resende escreveu"},"content":{"rendered":"<p><b>  <\/p>\n<p><\/b> &#8220;Se eu morrer, morre comigo um certo modo de ver, disse o poeta. Um poeta \u00e9  s\u00f3 isto: um certo modo de ver.&#8221;  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Se eu morrer, morre comigo um certo modo de ver, disse o poeta. Um poeta \u00e9 s\u00f3 isto: um certo modo de ver.&#8221;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8499","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8499"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8499\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}