{"id":8494,"date":"2013-08-05T12:00:00","date_gmt":"2013-08-05T15:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/autoestima\/"},"modified":"2013-08-05T12:00:00","modified_gmt":"2013-08-05T15:00:00","slug":"autoestima","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/autoestima\/","title":{"rendered":"Autoestima"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/b>   <\/p>\n<p>Consultados, psic\u00f3logos explicam. No fundo, o anor\u00e9xico n\u00e3o se ama. Sente-se  feio e incapaz de satisfazer expectativas nele depositadas. &#8220;\u00c9 a doen\u00e7a da  autoestima&#8221;, dizem eles. Os professores aproveitam a deixa. Ensinam duas li\u00e7\u00f5es.  Uma: o sentido de <i>auto<\/i>-. A diss\u00edlaba quer dizer <i>pr\u00f3prio<\/i>. Da\u00ed  autopromo\u00e7\u00e3o (promo\u00e7\u00e3o de si pr\u00f3prio), autodefesa (defesa de si pr\u00f3prio),  autodidata (professor de si mesmo).   <\/p>\n<p>A outra: a grafia das palavras escritas com <i>auto<\/i>-. Elas pedem h\u00edfen  quando <i>auto<\/i>&#8211; for seguido de <b>h<\/b> e <b>o<\/b>.<b> <\/b>Nos demais casos,  \u00e9 tudo colado ( auto-hipnose, auto-orienta\u00e7\u00e3o, autoavalia\u00e7\u00e3o, autoestrada,  autoescola, autorrealiza\u00e7\u00e3o, autossufici\u00eancia). <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consultados, psic\u00f3logos explicam. No fundo, o anor\u00e9xico n\u00e3o se ama. Sente-se feio e incapaz de satisfazer expectativas nele depositadas. &#8220;\u00c9 a doen\u00e7a da autoestima&#8221;, dizem eles. Os professores aproveitam a deixa. Ensinam duas li\u00e7\u00f5es. Uma: o sentido de auto-. A diss\u00edlaba quer dizer pr\u00f3prio. Da\u00ed autopromo\u00e7\u00e3o (promo\u00e7\u00e3o de si pr\u00f3prio), autodefesa (defesa de si pr\u00f3prio), autodidata (professor de si mesmo). A outra: a grafia das [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8494","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8494"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8494\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}