{"id":8474,"date":"2014-01-21T12:00:00","date_gmt":"2014-01-21T14:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-184\/"},"modified":"2015-11-13T10:18:59","modified_gmt":"2015-11-13T12:18:59","slug":"leitor_pergunta-184","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-184\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"<p><b> <\/b>  <\/p>\n<p>Um verbo virou moda no notici\u00e1rio policial. \u00c9 apreender, no  sentido de prender. No meu entendimento, apreender est\u00e1 ligado a tomar posse de  coisas, n\u00e3o de pessoas. Apreens\u00e3o de  mercadorias e pris\u00e3o de adolescentes. Poderia ser assim: a pol\u00edcia prendeu os  adolescentes e apreendeu o caiaque e coletes salva-vidas. (N\u00e9lia Marques de Oliveira) <\/p>\n<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p><\/b>  <\/p>\n<p>Lei \u00e9 lei, N\u00e9lia. O Estatuto da Crian\u00e7a do Adolescente  determina: menor de idade n\u00e3o \u00e9 preso. \u00c9 apreendido. Manda quem pode, obedece quem tem  ju\u00edzo.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um verbo virou moda no notici\u00e1rio policial. \u00c9 apreender, no sentido de prender. No meu entendimento, apreender est\u00e1 ligado a tomar posse de coisas, n\u00e3o de pessoas. Apreens\u00e3o de mercadorias e pris\u00e3o de adolescentes. Poderia ser assim: a pol\u00edcia prendeu os adolescentes e apreendeu o caiaque e coletes salva-vidas. (N\u00e9lia Marques de Oliveira) Lei \u00e9 lei, N\u00e9lia. O Estatuto da Crian\u00e7a do Adolescente determina: menor [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-8474","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8474"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8474\/revisions"}],"predecessor-version":[{"id":11265,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8474\/revisions\/11265"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}