{"id":8457,"date":"2014-01-20T15:39:00","date_gmt":"2014-01-20T17:39:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1099\/"},"modified":"2015-11-12T12:50:31","modified_gmt":"2015-11-12T14:50:31","slug":"erramos-1099-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-1099-2\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>&#8220;Em 2003,  o ex-ministro Ricardo Berzoini decidiu suspender o pagamento de todos os  benef\u00edcios dos segurados com 90 anos&#8221;, escrevemos na p\u00e1g. 9. Ops! Pisamos o  tempo. Ex-ministro j\u00e1 era. N\u00e3o faz nem acontece. Melhor&nbsp;corrigir: <i>Em 2003, o ent\u00e3o ministro Ricardo  Berzoini decidiu suspender o pagamento de todos os benef\u00edcios dos segurados com  90 anos<\/i>.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Em 2003, o ex-ministro Ricardo Berzoini decidiu suspender o pagamento de todos os benef\u00edcios dos segurados com 90 anos&#8221;, escrevemos na p\u00e1g. 9. Ops! Pisamos o tempo. Ex-ministro j\u00e1 era. N\u00e3o faz nem acontece. Melhor&nbsp;corrigir: Em 2003, o ent\u00e3o ministro Ricardo Berzoini decidiu suspender o pagamento de todos os benef\u00edcios dos segurados com 90 anos.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-8457","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8457"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8457\/revisions"}],"predecessor-version":[{"id":9660,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8457\/revisions\/9660"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}