{"id":8434,"date":"2013-07-31T17:30:00","date_gmt":"2013-07-31T20:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cochilos_da_revisao-49\/"},"modified":"2013-07-31T17:30:00","modified_gmt":"2013-07-31T20:30:00","slug":"cochilos_da_revisao-49","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cochilos_da_revisao-49\/","title":{"rendered":"Cochilos da revis\u00e3o"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Flat\u00f4nio Jos\u00e9 Da Silva  <\/p>\n<p>No t\u00edtulo &#8220;Menos beb\u00eas, mais idosos&#8221; (p. 19), saiu o  seguinte:<\/p><\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">1. &#8220;A mulher brasiliense, que antes tinha mais de dois filhos, hoje  <strong>t\u00eam<\/strong>, em m\u00e9dia, 1,8&#8243;. <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Corrigindo: A mulher brasiliense, que antes tinha mais de dois filhos,  hoje <strong>tem<\/strong>, em m\u00e9dia, 1,8.<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Explica\u00e7\u00e3o &#8212; Erro de concord\u00e2ncia: o sujeito no singular (a mulher  brasiliense) exige no verbo tamb\u00e9m no singular (tem).<\/p><\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">2. &#8220;Ter hor\u00e1rio para se alimentar e praticar exerc\u00edcios tamb\u00e9m  <strong>influenciam<\/strong> na qualidade de vidas  das pessoas&#8221;. <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Corrigindo: Ter hor\u00e1rio para se alimentar e praticar exerc\u00edcios tamb\u00e9m  <strong>influencia<\/strong> na qualidade de vida das  pessoas. <\/div>\n<div>\n<p>Explica\u00e7\u00e3o &#8212; Erro de concord\u00e2ncia: o sujeito constitu\u00eddo de infinitivos  leva o verbo para o singular: Andar e nadar faz bem \u00e0 sa\u00fade. Ler e  escrever \u00e9 suficiente para o trabalho que se disp\u00f5e a executar. <\/p><\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">3. &#8220;Ainda assim, o casal reclama da assist\u00eancia prec\u00e1ria \u00e0 sa\u00fade e  <strong>a<\/strong> falta de \u00e1reas de lazer para  idosos&#8221;. <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Corrigindo: Ainda assim, o casal reclama da assist\u00eancia prec\u00e1ria \u00e0  sa\u00fade e <strong>da<\/strong> falta de \u00e1reas de lazer  para idosos. <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Explica\u00e7\u00e3o &#8212; Erro de paralelismo. O casal reclama de duas coisas: (1)  <strong>da<\/strong> assist\u00eancia prec\u00e1ria \u00e0 sa\u00fade: (2) <strong>da<\/strong> falta  de \u00e1reas de lazer para idosos. <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">4. &#8220;<strong>Mas<\/strong> ainda assim, a  popula\u00e7\u00e3o, de maneira geral, continuar\u00e1 a envelhecer nos pr\u00f3ximos 20 anos&#8221;.  <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Corrigindo: <strong>Mas,<\/strong> ainda  assim, a popula\u00e7\u00e3o, de maneira geral, continuar\u00e1 a envelhecer nos pr\u00f3ximos 20  anos. <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Explica\u00e7\u00e3o &#8212; Erro de pontua\u00e7\u00e3o: a express\u00e3o intercalada &#8220;ainda assim&#8221; exige  duas v\u00edrgulas. <\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Flat\u00f4nio Jos\u00e9 Da Silva No t\u00edtulo &#8220;Menos beb\u00eas, mais idosos&#8221; (p. 19), saiu o seguinte: &nbsp; 1. &#8220;A mulher brasiliense, que antes tinha mais de dois filhos, hoje t\u00eam, em m\u00e9dia, 1,8&#8243;. Corrigindo: A mulher brasiliense, que antes tinha mais de dois filhos, hoje tem, em m\u00e9dia, 1,8. Explica\u00e7\u00e3o &#8212; Erro de concord\u00e2ncia: o sujeito no singular (a mulher brasiliense) exige no verbo tamb\u00e9m no [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8434","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8434"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8434\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}