{"id":8426,"date":"2014-10-08T00:00:00","date_gmt":"2014-10-08T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/boca_de_urna_e_boca_de_povo_4\/"},"modified":"2014-10-08T00:00:00","modified_gmt":"2014-10-08T03:00:00","slug":"boca_de_urna_e_boca_de_povo_4","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/boca_de_urna_e_boca_de_povo_4\/","title":{"rendered":"Boca de urna e boca de povo 4"},"content":{"rendered":"<p><b>   <\/p>\n<p>&#8230;e&nbsp;tr\u00eas  regras<\/b>   <\/p>\n<p>1. A  l\u00edngua \u00e9 um serzinho arteiro. Vers\u00e1til, muda de forma e de lugar. \u00c0s vezes, o  verbo vem antes do n\u00famero. A\u00ed,&nbsp;concorda  com o n\u00famero: Talvez consiga promo\u00e7\u00e3o 1% dos funcion\u00e1rios.&nbsp;Na elei\u00e7\u00e3o, renovaram-se 43% dos deputados. Perderam-se 20%  da safra de gr\u00e3os.       <\/p>\n<p>2.  Cuidado! N\u00e3o caia em armadilhas. Se s\u00f3 existe o n\u00famero, o verbo n\u00e3o tem  sa\u00edda. Acerta-se com ele: Os alunos tiveram rendimentos diferentes: 80%  conseguiram notas acima de 8; 12% ficaram com 9; s\u00f3&nbsp;1% gabaritou a  prova. Da popula\u00e7\u00e3o, 40% aprovaram o governo.       <\/p>\n<p>3. Se o  n\u00famero vem acompanhado de artigo ou pronome, ele dita a regra: <i>Os 70% da  popula\u00e7\u00e3o aprovaram a medida. Aqueles 5% da tropa desertaram.<\/i> <i>O 1% dos  candidatos desistiu do concurso.<\/i>    <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> &nbsp; Nobel<\/b>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;e&nbsp;tr\u00eas regras 1. A l\u00edngua \u00e9 um serzinho arteiro. Vers\u00e1til, muda de forma e de lugar. \u00c0s vezes, o verbo vem antes do n\u00famero. A\u00ed,&nbsp;concorda com o n\u00famero: Talvez consiga promo\u00e7\u00e3o 1% dos funcion\u00e1rios.&nbsp;Na elei\u00e7\u00e3o, renovaram-se 43% dos deputados. Perderam-se 20% da safra de gr\u00e3os. 2. Cuidado! N\u00e3o caia em armadilhas. Se s\u00f3 existe o n\u00famero, o verbo n\u00e3o tem sa\u00edda. Acerta-se com ele: Os [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8426","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8426"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8426\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}