{"id":8417,"date":"2014-05-13T10:00:00","date_gmt":"2014-05-13T13:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/procura-se_amigo_\/"},"modified":"2014-05-13T10:00:00","modified_gmt":"2014-05-13T13:00:00","slug":"procura-se_amigo_","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/procura-se_amigo_\/","title":{"rendered":"Procura-se amigo"},"content":{"rendered":"<p><a href=\"http:\/\/stat.correioweb.com.br\/blogs\/PROCURA-SEAMIGO.pps\" target=\"_blank\">http:\/\/stat.correioweb.com.br\/blogs\/PROCURA-SEAMIGO.pps<\/a> <\/p>\n<p>(Colabora\u00e7\u00e3o: Leda Watson)  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>http:\/\/stat.correioweb.com.br\/blogs\/PROCURA-SEAMIGO.pps (Colabora\u00e7\u00e3o: Leda Watson)<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8417","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8417"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8417\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}