{"id":8345,"date":"2013-04-03T16:50:00","date_gmt":"2013-04-03T19:50:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cochilos_da_revisao-45\/"},"modified":"2013-04-03T16:50:00","modified_gmt":"2013-04-03T19:50:00","slug":"cochilos_da_revisao-45","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cochilos_da_revisao-45\/","title":{"rendered":"Cochilos da revis\u00e3o"},"content":{"rendered":"<div class=\"WordSection1\">\n<p>Flat\u00f4nio Jos\u00e9 da Silva <\/p>\n<p>No t\u00edtulo \u201cUnB menos  rigorosa na sele\u00e7\u00e3o\u201d (Cidades, p. 21, 3\/4), saiu este  texto: &nbsp; <i>\u201cSe a universidade n\u00e3o  <b>rever<\/b> essa pontua\u00e7\u00e3o, n\u00e3o cumpre o que  determina a Lei das Cotas.\u201d<\/i>   <\/p>\n<p>Corrigindo: <i>Se a  universidade n\u00e3o <b>revir<\/b> essa  pontua\u00e7\u00e3o, n\u00e3o cumpre o que determina a Lei das Cotas<\/i>.    <\/p>\n<p>Explica\u00e7\u00e3o \u2013 Erro de  conjuga\u00e7\u00e3o: o verbo \u201crever\u201d conjuga-se como \u201cver\u201d, do qual deriva. O futuro do  subjuntivo ser\u00e1: <i>se eu vir (revir), se tu vires (revires), se ele <b>vir  (revir)<\/b>, se n\u00f3s virmos (revirmos), se v\u00f3s virdes (revirdes), se eles virem  (revirem)<\/i>.  &nbsp; <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Flat\u00f4nio Jos\u00e9 da Silva No t\u00edtulo \u201cUnB menos rigorosa na sele\u00e7\u00e3o\u201d (Cidades, p. 21, 3\/4), saiu este texto: &nbsp; \u201cSe a universidade n\u00e3o rever essa pontua\u00e7\u00e3o, n\u00e3o cumpre o que determina a Lei das Cotas.\u201d Corrigindo: Se a universidade n\u00e3o revir essa pontua\u00e7\u00e3o, n\u00e3o cumpre o que determina a Lei das Cotas. Explica\u00e7\u00e3o \u2013 Erro de conjuga\u00e7\u00e3o: o verbo \u201crever\u201d conjuga-se como \u201cver\u201d, do qual [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8345","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8345"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8345\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}