{"id":8339,"date":"2014-10-03T15:45:00","date_gmt":"2014-10-03T18:45:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cochilos_da_revisao_2-10\/"},"modified":"2014-10-03T15:45:00","modified_gmt":"2014-10-03T18:45:00","slug":"cochilos_da_revisao_2-10","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cochilos_da_revisao_2-10\/","title":{"rendered":"Cochilos da revis\u00e3o 2"},"content":{"rendered":"\n<p>Flat\u00f4nio Jos\u00e9 da Silva<br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   <br style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">Na coluna Bras\u00edlia-DF, saiu o  seguinte: <\/p>\n<div><\/div>\n<p>&#8220;No Cear\u00e1, o motorista de um carro com propaganda do candidato a  governador<strong>, Camilo Santana, <\/strong>foi  detido com R$ 60 mil em dinheiro vivo&#8221;.  <\/p>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Corrigindo: No Cear\u00e1, o motorista de um carro com propaganda do  candidato a governador <strong>Camilo  Santana<\/strong> foi detido com R$ 60 mil em dinheiro vivo. <\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Explica\u00e7\u00e3o &#8211; Erro de pontua\u00e7\u00e3o: as v\u00edrgulas est\u00e3o sobrando porque &#8220;Camilo  Santana&#8221; n\u00e3o \u00e9 o \u00fanico candidato a governador do Cear\u00e1. Trata-se, pois, de um  termo restritivo, que rejeita as v\u00edrgulas. Se, contudo, o termo estivesse  determinado, a\u00ed sim as v\u00edrgulas fariam sentido porque estariam isolando um termo  explicativo, \u00fanico. Veja o exemplo: No Cear\u00e1, o motorista de um carro com  propaganda do candidato do PT a governador, Camilo Santana, foi detido com R$ 60  mil em dinheiro vivo.  <\/p>\n<p>Aten\u00e7\u00e3o =&gt; Existem v\u00e1rios candidatos a governador,  mas apenas um do PT. <\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Flat\u00f4nio Jos\u00e9 da Silva Na coluna Bras\u00edlia-DF, saiu o seguinte: &#8220;No Cear\u00e1, o motorista de um carro com propaganda do candidato a governador, Camilo Santana, foi detido com R$ 60 mil em dinheiro vivo&#8221;. Corrigindo: No Cear\u00e1, o motorista de um carro com propaganda do candidato a governador Camilo Santana foi detido com R$ 60 mil em dinheiro vivo. Explica\u00e7\u00e3o &#8211; Erro de pontua\u00e7\u00e3o: as [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8339","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8339"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8339\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}