{"id":8331,"date":"2014-01-09T12:00:00","date_gmt":"2014-01-09T14:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/conversa_de_adolescentes\/"},"modified":"2014-01-09T12:00:00","modified_gmt":"2014-01-09T14:00:00","slug":"conversa_de_adolescentes","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/conversa_de_adolescentes\/","title":{"rendered":"Conversa de adolescentes"},"content":{"rendered":"<div>\n<p>Marcelo Abreu  <\/p>\n<p>Como diria o gaiato do alagoano Ancelmo Gois, &#8220;h\u00e1 testemunhas&#8221;. Estava agora  h\u00e1 pouco tomando um caf\u00e9 com meu amigo quando, de repente, chegaram duas  adolescentes. Sem errar, deviam ter entre 15 e 16 anos. No m\u00e1ximo, 17.  Sentaram-se ao nosso lado.  <\/p>\n<p>Adolescente fala alto. N\u00e3o tem pudores. Nem se  importa com quem escuta. No meio da conversa, entre uma teclada e outra no  telefone dela, a ruivinha de olhos gra\u00fados disse para a morena:  <\/p>\n<p>&#8212; V\u00e9i, como \u00e9 que se escreve ansioso?  <\/p>\n<p>A morena, meio sem certeza, respondeu:  <\/p>\n<p>&#8211; Sei l\u00e1, cara. Acho que \u00e9 com &#8220;c&#8221;.  <\/p>\n<p>A ruivinha, cheia de raz\u00e3o, disse:   <\/p>\n<p>&#8211;  Porra, v\u00e9i, o corretor do meu celular \u00e9 muito burro. Aqui t\u00e9 escrito com  &#8220;s&#8221;. Telefone sem no\u00e7\u00e3o, esse.  <\/p>\n<p>Ent\u00e3o, t\u00e1&#8230; Sobrou pro burro do  corretor. Ah, maldade!<\/p><\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Marcelo Abreu Como diria o gaiato do alagoano Ancelmo Gois, &#8220;h\u00e1 testemunhas&#8221;. Estava agora h\u00e1 pouco tomando um caf\u00e9 com meu amigo quando, de repente, chegaram duas adolescentes. Sem errar, deviam ter entre 15 e 16 anos. No m\u00e1ximo, 17. Sentaram-se ao nosso lado. Adolescente fala alto. N\u00e3o tem pudores. Nem se importa com quem escuta. No meio da conversa, entre uma teclada e outra [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8331","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8331"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8331\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}