{"id":8320,"date":"2014-05-07T00:01:00","date_gmt":"2014-05-07T03:01:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/loucuras_verde-amarelas\/"},"modified":"2014-05-07T00:01:00","modified_gmt":"2014-05-07T03:01:00","slug":"loucuras_verde-amarelas","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/loucuras_verde-amarelas\/","title":{"rendered":"Loucuras verde-amarelas"},"content":{"rendered":"\n<p> O Brasil enlouqueceu? N\u00e3o. Mas h\u00e1 comportamentos muito  doidos. Valem dois exemplos. Um vem de Recife. No Est\u00e1dio Arruda, vaso sanit\u00e1rio  voa e mata torcedor que tira foto da torcida. O outro, do Guaruj\u00e1: justiceiros  lincham dona de casa. Por qu\u00ea? Confundem-na com retrato falado de sequestradora  de crian\u00e7as. Simples assim.  <\/p>\n<p>Al\u00e9m de indigna\u00e7\u00e3o e protestos, os crimes suscitaram  d\u00favidas. Uma sobre grafia. <i>Voa<\/i> tem acento? N\u00e3o. A diss\u00edlaba joga no time  de <i>pessoa, perdoa, aben\u00e7oa, coroa<\/i>. Em todas aparece o hiato o\/a. Ele \u00e9  irm\u00e3ozinho de o\/o (voo, coroo, aben\u00e7oo, coroo). A fam\u00edlia tem um denominador  comum \u2014adora a leveza. Anda livre e solta, sem len\u00e7o e sem documento.    <\/p>\n<p>Outra quest\u00e3o: qual a origem da palavra linchar? O voc\u00e1bulo  deriva de nome de pessoa. William Lynch, l\u00e1 por 1.776, criou tribunal pra l\u00e1 de  cruel. Sem julgamento s\u00e9rio, condenava criminosos a morte por enforcamento. A  Lei de Lynch fez escola e ganhou adeptos. Grupo de pessoas sente-se no direito  de fazer justi\u00e7a com as pr\u00f3prias. Mata antes,  pergunta depois. \u00c9 a barb\u00e1rie.&nbsp;Valha-nos, Deus! <b><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil enlouqueceu? N\u00e3o. Mas h\u00e1 comportamentos muito doidos. Valem dois exemplos. Um vem de Recife. No Est\u00e1dio Arruda, vaso sanit\u00e1rio voa e mata torcedor que tira foto da torcida. O outro, do Guaruj\u00e1: justiceiros lincham dona de casa. Por qu\u00ea? Confundem-na com retrato falado de sequestradora de crian\u00e7as. Simples assim. Al\u00e9m de indigna\u00e7\u00e3o e protestos, os crimes suscitaram d\u00favidas. Uma sobre grafia. Voa tem [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8320","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8320"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8320\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}