{"id":8288,"date":"2013-04-02T09:00:00","date_gmt":"2013-04-02T12:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/xo_satanas-3\/"},"modified":"2013-04-02T09:00:00","modified_gmt":"2013-04-02T12:00:00","slug":"xo_satanas-3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/xo_satanas-3\/","title":{"rendered":"X\u00f4, satan\u00e1s!"},"content":{"rendered":"<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>Pode? Pode. O pior pode piorar. Marco Feliciano serve de prova. O deputado  foi eleito pra dirigir a Comiss\u00e3o de Direitos Humanos e Minorias da C\u00e2mara dos Deputados. Mas falta-lhe  perfil para t\u00e3o delicado cargo. O homem fez discursos racistas e hom\u00f3fobos.  Diante da rea\u00e7\u00e3o indignada de gregos, troianos e baianos, n\u00e3o se intimidou.  Disse que, at\u00e9 ele chegar, satan\u00e1s comandava a comiss\u00e3o. Isso mesmo \u2014 satan\u00e1s.    <\/p>\n<p>Pra se safar, apelou pra etimologia da palavra. Disse que, na origem, a  triss\u00edlaba signficava advers\u00e1rio. \u00c9 verdade. No hebraico, ber\u00e7o da criatura,  sat\u00e3 (satan\u00e1s) era termo jur\u00eddico. Designava o promotor no tribunal. Com o  tempo, por\u00e9m, a hist\u00f3ria mudou de enredo. Pouco antes da chegada de Cristo,  passou a dar nome a uma for\u00e7a sobrenatural e maligna.   <\/p>\n<p>Vale a pergunta: Marco Feliciano, em pleno s\u00e9culo 21, ter\u00e1 voltado no tempo?  Vai ver que quis mostrar erudi\u00e7\u00e3o \u2014 provar que sabe das coisas. N\u00e3o convenceu.  X\u00f4!<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pode? Pode. O pior pode piorar. Marco Feliciano serve de prova. O deputado foi eleito pra dirigir a Comiss\u00e3o de Direitos Humanos e Minorias da C\u00e2mara dos Deputados. Mas falta-lhe perfil para t\u00e3o delicado cargo. O homem fez discursos racistas e hom\u00f3fobos. Diante da rea\u00e7\u00e3o indignada de gregos, troianos e baianos, n\u00e3o se intimidou. Disse que, at\u00e9 ele chegar, satan\u00e1s comandava a comiss\u00e3o. Isso mesmo [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8288","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8288"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8288\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}