{"id":8195,"date":"2013-07-18T13:00:00","date_gmt":"2013-07-18T16:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_provocacao\/"},"modified":"2013-07-18T13:00:00","modified_gmt":"2013-07-18T16:00:00","slug":"e_provocacao","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e_provocacao\/","title":{"rendered":"\u00c9 provoca\u00e7\u00e3o"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p><\/b> &#8220;A m\u00e3e do filho do seu pai que n\u00e3o \u00e9 a sua m\u00e3e mas fica acordada se voc\u00ea n\u00e3o  chega.&#8221; Como \u00e9? Trata-se de texto publicit\u00e1rio para divulgar a nova temporada de  <i>Malha\u00e7\u00e3o<\/i>. Leitores fizeram o que t\u00eam de fazer. Leram. Alguns pararam e  releram&nbsp;a frase. Tornaram a l\u00ea-la. S\u00f3 ent\u00e3o&nbsp;a entenderam. Outros nem deram bola pra  brincadeirinha. Passaram adiante.   <\/p>\n<p>E voc\u00ea? Ganha um bombom Godiva se tiver decifrado a mensagem na primeira  passada d\u00b4olhos. Talvez tenha precisado voltar atr\u00e1s \u2014 uma, duas vezes. Feito  isso, oba! A m\u00e3e do filho do seu pai que n\u00e3o \u00e9 sua m\u00e3e \u00e9 \u2026 sua madrasta. Ou, se  preferir, a namorada do papai. Ou, ainda, sua segunda m\u00e3e. Convenhamos: a frase  n\u00e3o prima pela clareza. Prima pela provoca\u00e7\u00e3o. Chegou aonde quis chegar.  <b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> &nbsp;<\/b>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;A m\u00e3e do filho do seu pai que n\u00e3o \u00e9 a sua m\u00e3e mas fica acordada se voc\u00ea n\u00e3o chega.&#8221; Como \u00e9? Trata-se de texto publicit\u00e1rio para divulgar a nova temporada de Malha\u00e7\u00e3o. Leitores fizeram o que t\u00eam de fazer. Leram. Alguns pararam e releram&nbsp;a frase. Tornaram a l\u00ea-la. S\u00f3 ent\u00e3o&nbsp;a entenderam. Outros nem deram bola pra brincadeirinha. Passaram adiante. E voc\u00ea? Ganha um bombom [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8195","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=8195"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/8195\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=8195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=8195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=8195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}