{"id":7974,"date":"2013-06-22T00:00:00","date_gmt":"2013-06-22T03:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/licao_das_ruas_6\/"},"modified":"2013-06-22T00:00:00","modified_gmt":"2013-06-22T03:00:00","slug":"licao_das_ruas_6","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/licao_das_ruas_6\/","title":{"rendered":"li\u00e7\u00e3o das ruas 6"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">      <\/p>\n<p>   <\/b>  Ops!  Depois da confus\u00e3o em Fortaleza, o coment\u00e1rio que mais  se ouviu foi  este: &#8220;Nos jogos da Sele\u00e7\u00e3o, h\u00e1 bastante chances de haver  protestos&#8221;. A  profecia merce nota 10. Mas o portugu\u00eas\u2026 Bastante joga em  dois times: no dos adjetivos e no dos adv\u00e9rbios. <\/p>\n<p>      Adjetivo: ao modificar o substantivo,&nbsp;bastante entra na vala comum. Concorda  em n\u00famero com o nome. Na d\u00favida, basta substituir o triss\u00edlabo pelo diss\u00edlabo  (muito, muitos, muita, muitas): <i>Nos   jogos da Sele\u00e7\u00e3o, h\u00e1 bastantes (muitas) chances de haver protestos. O  governo  ter\u00e1 bastantes (muitos) recursos para atender as reivindica\u00e7\u00f5es  dos brasileiros?  Houve bastantes (muitas) demonstra\u00e7\u00f5es de  insatisfa\u00e7\u00e3o.<\/i> <\/p>\n<p>2.Adv\u00e9rbio: ao modificar o verbo, o adjetivo ou o adv\u00e9rbio,      bastante brinca de est\u00e1tua. Fica invari\u00e1vel. No troca-troca, s\u00f3 o muito tem vez:  Correu bastante (muito). Maria \u00e9  bastante&nbsp;(muito) r\u00e1pida na execu\u00e7\u00e3o das  tarefas. Minha casa fica bastante&nbsp;(muito)      longe das manifesta\u00e7\u00f5es. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ops! Depois da confus\u00e3o em Fortaleza, o coment\u00e1rio que mais se ouviu foi este: &#8220;Nos jogos da Sele\u00e7\u00e3o, h\u00e1 bastante chances de haver protestos&#8221;. A profecia merce nota 10. Mas o portugu\u00eas\u2026 Bastante joga em dois times: no dos adjetivos e no dos adv\u00e9rbios. Adjetivo: ao modificar o substantivo,&nbsp;bastante entra na vala comum. Concorda em n\u00famero com o nome. Na d\u00favida, basta substituir o triss\u00edlabo [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7974","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7974"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7974\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}