{"id":7955,"date":"2013-06-20T13:05:00","date_gmt":"2013-06-20T16:05:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/licao_das_ruas_2\/"},"modified":"2013-06-20T13:05:00","modified_gmt":"2013-06-20T16:05:00","slug":"licao_das_ruas_2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/licao_das_ruas_2\/","title":{"rendered":"Li\u00e7\u00e3o das ruas 2"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p><\/b> Uiiiiiiiiiiiiiiiiiiiii! O emprego do <b>z<\/b>, do <b>s<\/b>,  do<b> ss<\/b> e do <b>\u00e7<\/b> provocam baita dor de cabe\u00e7a. A raz\u00e3o: existem poucas  regras e muitas exce\u00e7\u00f5es. A vit\u00f3ria das ruas contribuiu para jogar luz em uma  das normas. Ao reduzir o pre\u00e7o das passagens, entrou em cartaz o <b>\u00e7<\/b>.  Substantivos derivados de verbos terminados em -uzir escrevem-se com \u00e7:    <i>reduzir (redu\u00e7\u00e3o), produzir (produ\u00e7\u00e3o), seduzir (sedu\u00e7\u00e3o), traduzir  (tradu\u00e7\u00e3o), conduzir (condu\u00e7\u00e3o).<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uiiiiiiiiiiiiiiiiiiiii! O emprego do z, do s, do ss e do \u00e7 provocam baita dor de cabe\u00e7a. A raz\u00e3o: existem poucas regras e muitas exce\u00e7\u00f5es. A vit\u00f3ria das ruas contribuiu para jogar luz em uma das normas. Ao reduzir o pre\u00e7o das passagens, entrou em cartaz o \u00e7. Substantivos derivados de verbos terminados em -uzir escrevem-se com \u00e7: reduzir (redu\u00e7\u00e3o), produzir (produ\u00e7\u00e3o), seduzir (sedu\u00e7\u00e3o), traduzir [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7955","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7955"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7955\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}