{"id":7768,"date":"2013-09-26T12:30:00","date_gmt":"2013-09-26T15:30:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/sopa_de_letrinhas\/"},"modified":"2013-09-26T12:30:00","modified_gmt":"2013-09-26T15:30:00","slug":"sopa_de_letrinhas","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/sopa_de_letrinhas\/","title":{"rendered":"Sopa de letrinhas"},"content":{"rendered":"\n<div><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">   <\/p>\n<p><\/b> O Brasil tinha 30 partidos. Na semana passada, nasceram mais dois. Um deles:  o Solidariedade. O outro: o Partido Republicano da Ordem Social (Pros). O fato,  claro, mereceu manchetes e coment\u00e1rios. N\u00e3o faltou velho e conhecido pleonasmo.  \u00c9 o tal &#8220;criar novo&#8221;. Ora, s\u00f3 se cria o novo. N\u00e3o \u00e9 novo? Mude-se o verbo.  Talvez recriar. Ou ressuscitar. Ou, ainda, desenterrar.<b><\/b><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil tinha 30 partidos. Na semana passada, nasceram mais dois. Um deles: o Solidariedade. O outro: o Partido Republicano da Ordem Social (Pros). O fato, claro, mereceu manchetes e coment\u00e1rios. N\u00e3o faltou velho e conhecido pleonasmo. \u00c9 o tal &#8220;criar novo&#8221;. Ora, s\u00f3 se cria o novo. N\u00e3o \u00e9 novo? Mude-se o verbo. Talvez recriar. Ou ressuscitar. Ou, ainda, desenterrar.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7768","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7768"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7768\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}