{"id":7729,"date":"2013-09-24T12:15:00","date_gmt":"2013-09-24T15:15:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta_1-22\/"},"modified":"2015-11-13T10:19:13","modified_gmt":"2015-11-13T12:19:13","slug":"leitor_pergunta_1-22","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta_1-22\/","title":{"rendered":"Leitor pergunta 1"},"content":{"rendered":"<p><b> <\/b>  <\/p>\n<p>Sendo r\u00e1pido e certeiro como o ataque do Cruzeiro. Trata-se  da pron\u00fancia de Iphan. Digo Ifam ou Ipam?(Gabriel Landim) <\/p>\n<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p><\/b> Diga alto e bom som Ifam. \u00c9 assim que a sigla se  escuta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sendo r\u00e1pido e certeiro como o ataque do Cruzeiro. Trata-se da pron\u00fancia de Iphan. Digo Ifam ou Ipam?(Gabriel Landim) Diga alto e bom som Ifam. \u00c9 assim que a sigla se escuta.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-7729","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7729"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7729\/revisions"}],"predecessor-version":[{"id":11285,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7729\/revisions\/11285"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}