{"id":7672,"date":"2013-09-18T11:00:00","date_gmt":"2013-09-18T14:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-969\/"},"modified":"2015-11-12T15:14:10","modified_gmt":"2015-11-12T17:14:10","slug":"erramos-969","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-969\/","title":{"rendered":"Erramos"},"content":{"rendered":"\n<p>&#8220;O chamado &#8220;risco Denitt&#8221;, como foi batizado pelo mercado, acarreta  preju\u00edzo ao tr\u00e1fego&#8221;, escrevemos na p\u00e1g. 11. Reparou na overdose? O modismo  (chamado) e as aspas sobraram. Melhor devolver a leveza \u00e0 frase. Assim: <i>O  risco Denitt, como foi batizado pelo mercado, acarreta preju\u00edzo ao tr\u00e1fego. <\/p>\n<p><\/i>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O chamado &#8220;risco Denitt&#8221;, como foi batizado pelo mercado, acarreta preju\u00edzo ao tr\u00e1fego&#8221;, escrevemos na p\u00e1g. 11. Reparou na overdose? O modismo (chamado) e as aspas sobraram. Melhor devolver a leveza \u00e0 frase. Assim: O risco Denitt, como foi batizado pelo mercado, acarreta preju\u00edzo ao tr\u00e1fego.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-7672","post","type-post","status-publish","format-standard","hentry","category-erramos","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7672"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7672\/revisions"}],"predecessor-version":[{"id":9719,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7672\/revisions\/9719"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}