{"id":7658,"date":"2013-09-17T14:00:00","date_gmt":"2013-09-17T17:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/colaboracao\/"},"modified":"2013-09-17T14:00:00","modified_gmt":"2013-09-17T17:00:00","slug":"colaboracao","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/colaboracao\/","title":{"rendered":"Colabora\u00e7\u00e3o"},"content":{"rendered":"\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"><strong>  <\/p>\n<p>Rold\u00e3o Simas Filho <\/p>\n<p>Gostaria de comentar o post &#8220;Farinha do mesmo  saco&#8221;:<\/strong><\/div>\n<div><strong><\/strong>&nbsp;<\/div>\n<div><strong>P\u00e9 na  jaca&nbsp;&nbsp;\u00e9 express\u00e3o curiosa cuja origem \u00e9 incompreens\u00edvel.&nbsp; Isso ocorre  porque, na verdade, foi alterada. N\u00e3o se&nbsp;trata de enfiar o p\u00e9 na jaca, algo sem  l\u00f3gica.&nbsp;A express\u00e3o correta \u00e9 &#8220;enfiar o p\u00e9 no jac\u00e1&#8221;.&nbsp;   <\/p>\n<p>Explica-se:&nbsp; nas antigas  quitandas, era comum expor as frutas num jac\u00e1 (cesto de vime) colocado  no ch\u00e3o, junto \u00e0 porta de entrada para ser bem vis\u00edvel. Mas, com isso,&nbsp;o  acesso das pessoas exigia cuidado para n\u00e3o&nbsp; trope\u00e7ar no jac\u00e1. Numa dessas  ocasi\u00f5es, algu\u00e9m, descuidado, enfiou o p\u00e9 no jac\u00e1, pisando as frutas&nbsp;que se  espalharam pelo ch\u00e3o. <\/strong><\/div>\n<div>&nbsp;<\/div>\n<div><strong>V\u00e1 plantar  batata no asfalto &#8212;&nbsp; Houve mistura entre duas express\u00f5es:&nbsp; ir plantar  batatas (as batatas eram desvalorizadas)- e catar minhoca no asfalto (onde  n\u00e3o h\u00e1 minhoca&nbsp;nem outro&nbsp;bicho). <\/strong>&nbsp;&nbsp;<\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rold\u00e3o Simas Filho Gostaria de comentar o post &#8220;Farinha do mesmo saco&#8221;: &nbsp; P\u00e9 na jaca&nbsp;&nbsp;\u00e9 express\u00e3o curiosa cuja origem \u00e9 incompreens\u00edvel.&nbsp; Isso ocorre porque, na verdade, foi alterada. N\u00e3o se&nbsp;trata de enfiar o p\u00e9 na jaca, algo sem l\u00f3gica.&nbsp;A express\u00e3o correta \u00e9 &#8220;enfiar o p\u00e9 no jac\u00e1&#8221;.&nbsp; Explica-se:&nbsp; nas antigas quitandas, era comum expor as frutas num jac\u00e1 (cesto de vime) colocado no ch\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7658","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7658"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7658\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}