{"id":7609,"date":"2013-05-14T13:10:00","date_gmt":"2013-05-14T16:10:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/infinito_enquanto_dura\/"},"modified":"2013-05-14T13:10:00","modified_gmt":"2013-05-14T16:10:00","slug":"infinito_enquanto_dura","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/infinito_enquanto_dura\/","title":{"rendered":"Infinito enquanto dura"},"content":{"rendered":"<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/p>\n<p><\/b> O mundo d\u00e1 voltas. L\u00e1 por 1960, Cuba mandava os homossexuais  pra campos de trabalho. Agora promove passeatas anti-homofobia. A psic\u00f3loga  Marieta Castro lidera o movimento. Ela n\u00e3o \u00e9 nem mais nem menos que filha de  Ra\u00fal Castro, presidente do pa\u00eds.   <\/p>\n<p>Ao noticiar o fato, perguntas pintaram a torto e a direito.  Uma delas: como se escreve anti-homofobia? Assim mesmo. Prefixos seguidos de h  pedem h\u00edfen sim, senhor: <i>super-homem, contra-hist\u00f3ria,  anti-hig\u00eanico<\/i>.<b> &nbsp;<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mundo d\u00e1 voltas. L\u00e1 por 1960, Cuba mandava os homossexuais pra campos de trabalho. Agora promove passeatas anti-homofobia. A psic\u00f3loga Marieta Castro lidera o movimento. Ela n\u00e3o \u00e9 nem mais nem menos que filha de Ra\u00fal Castro, presidente do pa\u00eds. Ao noticiar o fato, perguntas pintaram a torto e a direito. Uma delas: como se escreve anti-homofobia? Assim mesmo. Prefixos seguidos de h pedem [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7609","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=7609"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/7609\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=7609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=7609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=7609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}